{"id":4554,"date":"2022-01-19T18:27:19","date_gmt":"2022-01-19T17:27:19","guid":{"rendered":"https:\/\/parchotelgrittibardolino.it\/camere\/"},"modified":"2024-02-27T17:19:56","modified_gmt":"2024-02-27T16:19:56","slug":"zimmer","status":"publish","type":"page","link":"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/","title":{"rendered":"Zimmer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sind Sie auf der Suche nach <strong>der idealen Unterkunft<\/strong> f\u00fcr einen entspannten Aufenthalt am See in Bardolino?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Parc Hotel Gritti, ein 4-Sterne-Hotel nur 5 Minuten vom Zentrum von Bardolino entfernt, bietet Ihnen <strong>ger\u00e4umige und stilvolle Zimmer in ruhiger Lage<\/strong>, nur einen Schritt vom Ufer des Sees und seiner atemberaubenden Aussicht entfernt. W\u00e4hlen Sie die Zimmerkategorie, die Ihren W\u00fcnschen entspricht.<\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Wichtige Informationen<\/summary>\n<p class=\"wp-block-paragraph\">Reisen Sie mit Ihrem Tier an? Bitte, teilen Sie es uns mit bei der Buchung. Lesen Sie noch bitte unsere <a href=\"https:\/\/parchotelgrittibardolino.it\/de\/pet-friendly\/\">Regelung<\/a> durch, damit Sie, Ihr Vierbeiner und alle andere G\u00e4ste einen angenehmen Urlaub verbringen k\u00f6nnen. Alle Zimmer sind nichtraucher.<\/p>\n<\/details>\n","protected":false},"excerpt":{"rendered":"<p>Sind Sie auf der Suche nach der idealen Unterkunft f\u00fcr einen entspannten Aufenthalt am See in Bardolino? Das Parc Hotel Gritti, ein 4-Sterne-Hotel nur 5 Minuten vom Zentrum von Bardolino entfernt, bietet Ihnen ger\u00e4umige und stilvolle Zimmer in ruhiger Lage, nur einen Schritt vom Ufer des Sees und seiner atemberaubenden Aussicht entfernt. W\u00e4hlen Sie die [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":37,"comment_status":"closed","ping_status":"closed","template":"page-camere.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4554","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zimmer - Parc Hotel Gritti, Bardolino<\/title>\n<meta name=\"description\" content=\"Entdecken Sie alle Zimmertypen und buchen Sie Ihre Sommerurlaub am Gardasee.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zimmer - Parc Hotel Gritti, Bardolino\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie alle Zimmertypen und buchen Sie Ihre Sommerurlaub am Gardasee.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/\" \/>\n<meta property=\"og:site_name\" content=\"Parc Hotel Gritti\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-27T16:19:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/zimmer\\\/\",\"url\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/zimmer\\\/\",\"name\":\"Zimmer - Parc Hotel Gritti, Bardolino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/#website\"},\"datePublished\":\"2022-01-19T17:27:19+00:00\",\"dateModified\":\"2024-02-27T16:19:56+00:00\",\"description\":\"Entdecken Sie alle Zimmertypen und buchen Sie Ihre Sommerurlaub am Gardasee.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/zimmer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/zimmer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/zimmer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zimmer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/\",\"name\":\"Parc Hotel Gritti\",\"description\":\"Un nuovo sito targato WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/parchotelgrittibardolino.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zimmer - Parc Hotel Gritti, Bardolino","description":"Entdecken Sie alle Zimmertypen und buchen Sie Ihre Sommerurlaub am Gardasee.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/","og_locale":"de_DE","og_type":"article","og_title":"Zimmer - Parc Hotel Gritti, Bardolino","og_description":"Entdecken Sie alle Zimmertypen und buchen Sie Ihre Sommerurlaub am Gardasee.","og_url":"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/","og_site_name":"Parc Hotel Gritti","article_modified_time":"2024-02-27T16:19:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/","url":"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/","name":"Zimmer - Parc Hotel Gritti, Bardolino","isPartOf":{"@id":"https:\/\/parchotelgrittibardolino.it\/de\/#website"},"datePublished":"2022-01-19T17:27:19+00:00","dateModified":"2024-02-27T16:19:56+00:00","description":"Entdecken Sie alle Zimmertypen und buchen Sie Ihre Sommerurlaub am Gardasee.","breadcrumb":{"@id":"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/parchotelgrittibardolino.it\/de\/zimmer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/parchotelgrittibardolino.it\/de\/"},{"@type":"ListItem","position":2,"name":"Zimmer"}]},{"@type":"WebSite","@id":"https:\/\/parchotelgrittibardolino.it\/de\/#website","url":"https:\/\/parchotelgrittibardolino.it\/de\/","name":"Parc Hotel Gritti","description":"Un nuovo sito targato WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parchotelgrittibardolino.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/parchotelgrittibardolino.it\/de\/wp-json\/wp\/v2\/pages\/4554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parchotelgrittibardolino.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/parchotelgrittibardolino.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/parchotelgrittibardolino.it\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/parchotelgrittibardolino.it\/de\/wp-json\/wp\/v2\/comments?post=4554"}],"version-history":[{"count":14,"href":"https:\/\/parchotelgrittibardolino.it\/de\/wp-json\/wp\/v2\/pages\/4554\/revisions"}],"predecessor-version":[{"id":9753,"href":"https:\/\/parchotelgrittibardolino.it\/de\/wp-json\/wp\/v2\/pages\/4554\/revisions\/9753"}],"wp:attachment":[{"href":"https:\/\/parchotelgrittibardolino.it\/de\/wp-json\/wp\/v2\/media?parent=4554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}